{"id":9408,"date":"2025-02-17T10:59:56","date_gmt":"2025-02-17T10:59:56","guid":{"rendered":"https:\/\/herik.nl\/artikelen\/abbau-des-blindgaengers-claes-de-vrieselaan-rotterdam\/"},"modified":"2026-04-10T09:08:41","modified_gmt":"2026-04-10T09:08:41","slug":"abbau-des-blindgaengers-claes-de-vrieselaan-rotterdam","status":"publish","type":"artikelen","link":"https:\/\/herik.nl\/de\/artikelen\/abbau-des-blindgaengers-claes-de-vrieselaan-rotterdam\/","title":{"rendered":"ABBAU DES BLINDG\u00c4NGERS CLAES DE VRIESELAAN ROTTERDAM"},"content":{"rendered":"\n<section class=\"section-afbeelding-met-golfscheiding\">\n    \t\t<div data-elementor-type=\"section\" data-elementor-id=\"9435\" class=\"elementor elementor-9435 elementor-1442\" data-elementor-post-type=\"elementor_library\">\n\t\t\t<div class=\"elementor-element elementor-element-2c557bc e-con-full e-flex aw-Hintergrundgro\u00dfartig e-con e-parent\" data-id=\"2c557bc\" data-element_type=\"container\" data-e-type=\"container\" id=\"aw-hero-img\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7dc8102 elementor-widget elementor-widget-image\" data-id=\"7dc8102\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1920\" height=\"665\" src=\"https:\/\/herik.nl\/wp-content\/uploads\/2025\/02\/IMG-20240528-WA0029-drone-levi-banner.jpg\" class=\"attachment-full size-full wp-image-8794\" alt=\"\" srcset=\"https:\/\/herik.nl\/wp-content\/uploads\/2025\/02\/IMG-20240528-WA0029-drone-levi-banner.jpg 1920w, https:\/\/herik.nl\/wp-content\/uploads\/2025\/02\/IMG-20240528-WA0029-drone-levi-banner-300x104.jpg 300w, https:\/\/herik.nl\/wp-content\/uploads\/2025\/02\/IMG-20240528-WA0029-drone-levi-banner-1024x355.jpg 1024w, https:\/\/herik.nl\/wp-content\/uploads\/2025\/02\/IMG-20240528-WA0029-drone-levi-banner-768x266.jpg 768w, https:\/\/herik.nl\/wp-content\/uploads\/2025\/02\/IMG-20240528-WA0029-drone-levi-banner-1536x532.jpg 1536w, https:\/\/herik.nl\/wp-content\/uploads\/2025\/02\/IMG-20240528-WA0029-drone-levi-banner-574x199.jpg 574w, https:\/\/herik.nl\/wp-content\/uploads\/2025\/02\/IMG-20240528-WA0029-drone-levi-banner-1918x664.jpg 1918w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/section>\n<section class=\"section-titel-met-tekst-en-button-volledige-breedte\">\n    \t\t<div data-elementor-type=\"section\" data-elementor-id=\"9544\" class=\"elementor elementor-9544 elementor-297\" data-elementor-post-type=\"elementor_library\">\n\t\t\t<div class=\"elementor-element elementor-element-a15b6c7 e-con-full aw-kleur-wei\u00df  e-flex e-con e-parent\" data-id=\"a15b6c7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-61b1760 aw-subtext-container awBlok1 e-flex e-con-boxed e-con e-child\" data-id=\"61b1760\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d5de06c Titel Links elementor-widget elementor-widget-heading\" data-id=\"d5de06c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">DISMANTLING BLINDGANGER CLAES DE VRIESELAAN Rotterdam<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b12747 contentBlok1 elementor-widget elementor-widget-text-editor\" data-id=\"7b12747\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Nach monatelanger detaillierter Vorbereitung hat unser Team den Boden Schicht f\u00fcr Schicht ausgehoben, um sich dem Blindg\u00e4nger unter der Claes de Vrieselaan 27 zu n\u00e4hern. Und das mit Erfolg. Am 30. Mai 2024 wurde die Bombe entsch\u00e4rft. Die R\u00e4umung und Entsch\u00e4rfung erfolgt durch den Kampfmittelbeseitigungsdienst (EOD), aber bis es so weit war, wurde eine Menge Arbeit geleistet!  <\/strong><\/p>\n<p><strong>Was war vorher<br \/>\n<\/strong>Durch umfangreiche historische Recherchen der Spezialisten von Saricon wissen wir, dass in Rotterdam an etwa 200 Stellen ein erh\u00f6htes Risiko f\u00fcr das Vorhandensein einer nicht explodierten Fliegerbombe (auch Blindg\u00e4nger genannt) besteht. Das war auch in Claes de Vrieselaan der Fall. <\/p>\n<p>Ende 2016 haben wir mit Hilfe von Ortungsger\u00e4ten das wahrscheinliche Vorhandensein und die Lage eines Blindg\u00e4ngers best\u00e4tigt. Die Bombe liegt etwa 8 Meter unter der Erde und in einer solchen Tiefe kann eine solche Bombe oft gefahrlos an Ort und Stelle belassen werden. Im Fall von Claes de Vrieselaan war es jedoch notwendig, das Fundament zu reparieren. Daher beschloss der Stadtrat 2017, dass die Bombe ger\u00e4umt werden sollte.   <\/p>\n<p><a class=\"aw-text-arrow-right\" href=\"https:\/\/www.rotterdam.nl\/bommenkaart\" target=\"_blank\" rel=\"noopener\">Sie fragen sich, wo all diese Attraktionen zu finden sind? Sehen Sie es auf der Bomb Map Rotterdam nach. <\/a><\/p>\n<p><strong>Sondereinsatz<\/strong><br \/>\nEs kommt nicht oft vor, dass diese Art von Arbeit im Zentrum einer Stadt durchgef\u00fchrt wird. Die Entsch\u00e4rfung dieser Bombe wurde also \u00e4u\u00dferst sorgf\u00e4ltig vorbereitet. Es ist ein weitreichendes Ereignis.  <\/p>\n<p>Um die Bombe zu entfernen, mussten 3 Grundst\u00fccke (6 H\u00e4user) abgerissen werden. Der Abriss wurde im Herbst 2023 abgeschlossen. Anschlie\u00dfend f\u00fchrten wir in enger Zusammenarbeit mit der Stadt Rotterdam und dem EOD u.a. die erforderlichen Arbeiten zur Ausgrabung, Entsch\u00e4rfung, Entsorgung und schlie\u00dflich zur Zerst\u00f6rung der Bombe durch.   W\u00e4hrend der Keulung am 30. Mai m\u00fcssen etwa 1.100 Anwohner in der unmittelbaren Umgebung ihre H\u00e4user vorsorglich verlassen. Sicherheit geht vor! <\/p>\n<p><strong>Auch das ist laut EOD ein einzigartiger Job:<\/strong><br \/>\n&#8220;Normalerweise finden wir Sprengstoff auf offenen Fl\u00e4chen, in der N\u00e4he von Flugh\u00e4fen oder Hafengebieten, wo nur die Gesch\u00e4fte vor\u00fcbergehend geschlossen werden m\u00fcssen. Eine solche R\u00e4umung hat viel weniger Auswirkungen auf die Umgebung. Hier liegt der Blindg\u00e4nger mitten in einem Wohngebiet und 1.100 Menschen m\u00fcssen ihre H\u00e4user verlassen. Au\u00dferdem werden wir bis zum 30. Mai nicht mit Sicherheit wissen, mit welcher Art von Bombe und Z\u00fcnder wir es zu tun haben. Wir sind von einer Tausendpf\u00fcnderbombe ausgegangen, dem schwersten Kaliber mit dem gr\u00f6\u00dften Sprengstoff, damit wir am Donnerstag keine \u00dcberraschungen erleben.&#8220;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-7179 size-full\" src=\"https:\/\/herik.nl\/wp-content\/uploads\/2025\/02\/VDHERIK-CLAES-SANDER-NAGEL-2024-08908-crop.jpg\" alt=\"\" width=\"1200\" height=\"800\" srcset=\"https:\/\/herik.nl\/wp-content\/uploads\/2025\/02\/VDHERIK-CLAES-SANDER-NAGEL-2024-08908-crop.jpg 1200w, https:\/\/herik.nl\/wp-content\/uploads\/2025\/02\/VDHERIK-CLAES-SANDER-NAGEL-2024-08908-crop-300x200.jpg 300w, https:\/\/herik.nl\/wp-content\/uploads\/2025\/02\/VDHERIK-CLAES-SANDER-NAGEL-2024-08908-crop-1024x683.jpg 1024w, https:\/\/herik.nl\/wp-content\/uploads\/2025\/02\/VDHERIK-CLAES-SANDER-NAGEL-2024-08908-crop-768x512.jpg 768w, https:\/\/herik.nl\/wp-content\/uploads\/2025\/02\/VDHERIK-CLAES-SANDER-NAGEL-2024-08908-crop-574x383.jpg 574w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><br \/>\n<em>EOD untersucht Teile eines gefundenen Baumschwanzes<\/em><\/p>\n<p><strong>Pr\u00e4zisionsarbeit auf dem Quadratmeter<\/strong><br \/>\nEine Bombe, die etwa 8 Meter unter der Erde liegt, schaufelt man nicht einfach aus. Daf\u00fcr ist schweres Ger\u00e4t erforderlich. Um dieses schwere Ger\u00e4t in dem engen Raum zwischen den H\u00e4usern gut zu handhaben, ist unser Kran speziell f\u00fcr diese Arbeit mit einer hydraulischen Kabinenerh\u00f6hung und LMB (Lastmomentsicherung) ausgestattet. Diese hydraulische Kabine kann um 2,15 Meter angehoben werden, so dass der Bediener im Cockpit einen besseren Blick auf die Arbeit hat. Die LMB sorgt daf\u00fcr, dass wir sicher heben k\u00f6nnen.    <\/p>\n<p>Au\u00dferdem wurde in Zusammenarbeit mit der Firma Gebr. De Koning eine spezielle Kofferdamm-Konstruktion f\u00fcr diese besondere Arbeit entwickelt und installiert. Sie taten dies mit gro\u00dfer Pr\u00e4zision und in dem engen Raum um diese Bombe herum, fachm\u00e4nnisch und vibrationsfrei durch den Einsatz eines Silent Piler.  <\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-7180\" src=\"https:\/\/herik.nl\/wp-content\/uploads\/2025\/02\/VDHERIK-CLAES-SANDER-NAGEL-2024-08974-crop-1.jpg\" alt=\"\" width=\"1200\" height=\"800\" srcset=\"https:\/\/herik.nl\/wp-content\/uploads\/2025\/02\/VDHERIK-CLAES-SANDER-NAGEL-2024-08974-crop-1.jpg 1200w, https:\/\/herik.nl\/wp-content\/uploads\/2025\/02\/VDHERIK-CLAES-SANDER-NAGEL-2024-08974-crop-1-300x200.jpg 300w, https:\/\/herik.nl\/wp-content\/uploads\/2025\/02\/VDHERIK-CLAES-SANDER-NAGEL-2024-08974-crop-1-1024x683.jpg 1024w, https:\/\/herik.nl\/wp-content\/uploads\/2025\/02\/VDHERIK-CLAES-SANDER-NAGEL-2024-08974-crop-1-768x512.jpg 768w, https:\/\/herik.nl\/wp-content\/uploads\/2025\/02\/VDHERIK-CLAES-SANDER-NAGEL-2024-08974-crop-1-574x383.jpg 574w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><br \/>\n<em>Schichtweiser Aushub des Bodens bis zu einer Tiefe von etwa 8 Metern, wo sich der Blindg\u00e4nger befindet<\/em><\/p>\n<p><strong>Entsch\u00e4rfung<\/strong><br \/>\nNach jahrelanger Vorbereitung ist am Donnerstag, den 30. Mai, endlich der Tag gekommen. Das EOD gr\u00e4bt die Bombe aus, identifiziert sie und entsch\u00e4rft sie dann. Die Bombe kann dann sicher entfernt und entsorgt werden. Das EOD bringt die Bombe weg, um sie au\u00dferhalb der Stadt zu zerst\u00f6ren. Sobald das EOD fertig ist und die Bombe entsorgt hat, k\u00f6nnen die Bewohner in ihre H\u00e4user zur\u00fcckkehren.    <\/p>\n<p><strong>Nat\u00fcrlich sorgen wir anschlie\u00dfend daf\u00fcr, dass das riesige Loch wieder sauber verschlossen wird, so dass mit den Fundamentarbeiten sicher begonnen werden kann.<\/strong><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/section>","protected":false},"excerpt":{"rendered":"<p>Nach monatelanger detaillierter Vorbereitung hat unser Team den Boden Schicht f\u00fcr Schicht ausgehoben, um sich dem Blindg\u00e4nger unter der Claes de Vrieselaan 27 zu n\u00e4hern.<\/p>\n","protected":false},"featured_media":8794,"template":"","categories":[119],"tags":[],"class_list":["post-9408","artikelen","type-artikelen","status-publish","has-post-thumbnail","hentry","category-sprengstoff-detektion"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ABBAU DES BLINDG\u00c4NGERS CLAES DE VRIESELAAN ROTTERDAM - van den Herik Sliedrecht<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/herik.nl\/de\/artikelen\/abbau-des-blindgaengers-claes-de-vrieselaan-rotterdam\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ABBAU DES BLINDG\u00c4NGERS CLAES DE VRIESELAAN ROTTERDAM - van den Herik Sliedrecht\" \/>\n<meta property=\"og:description\" content=\"Nach monatelanger detaillierter Vorbereitung hat unser Team den Boden Schicht f\u00fcr Schicht ausgehoben, um sich dem Blindg\u00e4nger unter der Claes de Vrieselaan 27 zu n\u00e4hern.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/herik.nl\/de\/artikelen\/abbau-des-blindgaengers-claes-de-vrieselaan-rotterdam\/\" \/>\n<meta property=\"og:site_name\" content=\"van den Herik Sliedrecht\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-10T09:08:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/herik.nl\/wp-content\/uploads\/2025\/02\/IMG-20240528-WA0029-drone-levi-banner.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"665\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/herik.nl\\\/de\\\/artikelen\\\/abbau-des-blindgaengers-claes-de-vrieselaan-rotterdam\\\/\",\"url\":\"https:\\\/\\\/herik.nl\\\/de\\\/artikelen\\\/abbau-des-blindgaengers-claes-de-vrieselaan-rotterdam\\\/\",\"name\":\"ABBAU DES BLINDG\u00c4NGERS CLAES DE VRIESELAAN ROTTERDAM - van den Herik Sliedrecht\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/herik.nl\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/herik.nl\\\/de\\\/artikelen\\\/abbau-des-blindgaengers-claes-de-vrieselaan-rotterdam\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/herik.nl\\\/de\\\/artikelen\\\/abbau-des-blindgaengers-claes-de-vrieselaan-rotterdam\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/herik.nl\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/IMG-20240528-WA0029-drone-levi-banner.jpg\",\"datePublished\":\"2025-02-17T10:59:56+00:00\",\"dateModified\":\"2026-04-10T09:08:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/herik.nl\\\/de\\\/artikelen\\\/abbau-des-blindgaengers-claes-de-vrieselaan-rotterdam\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/herik.nl\\\/de\\\/artikelen\\\/abbau-des-blindgaengers-claes-de-vrieselaan-rotterdam\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/herik.nl\\\/de\\\/artikelen\\\/abbau-des-blindgaengers-claes-de-vrieselaan-rotterdam\\\/#primaryimage\",\"url\":\"https:\\\/\\\/herik.nl\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/IMG-20240528-WA0029-drone-levi-banner.jpg\",\"contentUrl\":\"https:\\\/\\\/herik.nl\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/IMG-20240528-WA0029-drone-levi-banner.jpg\",\"width\":1920,\"height\":665},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/herik.nl\\\/de\\\/artikelen\\\/abbau-des-blindgaengers-claes-de-vrieselaan-rotterdam\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/herik.nl\\\/de\\\/voorbeeld-pagina\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Actueel\",\"item\":\"https:\\\/\\\/herik.nl\\\/de\\\/artikelen\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"ABBAU DES BLINDG\u00c4NGERS CLAES DE VRIESELAAN ROTTERDAM\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/herik.nl\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/herik.nl\\\/de\\\/\",\"name\":\"van den Herik Sliedrecht\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/herik.nl\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ABBAU DES BLINDG\u00c4NGERS CLAES DE VRIESELAAN ROTTERDAM - van den Herik Sliedrecht","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/herik.nl\/de\/artikelen\/abbau-des-blindgaengers-claes-de-vrieselaan-rotterdam\/","og_locale":"de_DE","og_type":"article","og_title":"ABBAU DES BLINDG\u00c4NGERS CLAES DE VRIESELAAN ROTTERDAM - van den Herik Sliedrecht","og_description":"Nach monatelanger detaillierter Vorbereitung hat unser Team den Boden Schicht f\u00fcr Schicht ausgehoben, um sich dem Blindg\u00e4nger unter der Claes de Vrieselaan 27 zu n\u00e4hern.","og_url":"https:\/\/herik.nl\/de\/artikelen\/abbau-des-blindgaengers-claes-de-vrieselaan-rotterdam\/","og_site_name":"van den Herik Sliedrecht","article_modified_time":"2026-04-10T09:08:41+00:00","og_image":[{"width":1920,"height":665,"url":"https:\/\/herik.nl\/wp-content\/uploads\/2025\/02\/IMG-20240528-WA0029-drone-levi-banner.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/herik.nl\/de\/artikelen\/abbau-des-blindgaengers-claes-de-vrieselaan-rotterdam\/","url":"https:\/\/herik.nl\/de\/artikelen\/abbau-des-blindgaengers-claes-de-vrieselaan-rotterdam\/","name":"ABBAU DES BLINDG\u00c4NGERS CLAES DE VRIESELAAN ROTTERDAM - van den Herik Sliedrecht","isPartOf":{"@id":"https:\/\/herik.nl\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/herik.nl\/de\/artikelen\/abbau-des-blindgaengers-claes-de-vrieselaan-rotterdam\/#primaryimage"},"image":{"@id":"https:\/\/herik.nl\/de\/artikelen\/abbau-des-blindgaengers-claes-de-vrieselaan-rotterdam\/#primaryimage"},"thumbnailUrl":"https:\/\/herik.nl\/wp-content\/uploads\/2025\/02\/IMG-20240528-WA0029-drone-levi-banner.jpg","datePublished":"2025-02-17T10:59:56+00:00","dateModified":"2026-04-10T09:08:41+00:00","breadcrumb":{"@id":"https:\/\/herik.nl\/de\/artikelen\/abbau-des-blindgaengers-claes-de-vrieselaan-rotterdam\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/herik.nl\/de\/artikelen\/abbau-des-blindgaengers-claes-de-vrieselaan-rotterdam\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/herik.nl\/de\/artikelen\/abbau-des-blindgaengers-claes-de-vrieselaan-rotterdam\/#primaryimage","url":"https:\/\/herik.nl\/wp-content\/uploads\/2025\/02\/IMG-20240528-WA0029-drone-levi-banner.jpg","contentUrl":"https:\/\/herik.nl\/wp-content\/uploads\/2025\/02\/IMG-20240528-WA0029-drone-levi-banner.jpg","width":1920,"height":665},{"@type":"BreadcrumbList","@id":"https:\/\/herik.nl\/de\/artikelen\/abbau-des-blindgaengers-claes-de-vrieselaan-rotterdam\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/herik.nl\/de\/voorbeeld-pagina\/"},{"@type":"ListItem","position":2,"name":"Actueel","item":"https:\/\/herik.nl\/de\/artikelen\/"},{"@type":"ListItem","position":3,"name":"ABBAU DES BLINDG\u00c4NGERS CLAES DE VRIESELAAN ROTTERDAM"}]},{"@type":"WebSite","@id":"https:\/\/herik.nl\/de\/#website","url":"https:\/\/herik.nl\/de\/","name":"van den Herik Sliedrecht","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/herik.nl\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/herik.nl\/de\/wp-json\/wp\/v2\/artikelen\/9408","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/herik.nl\/de\/wp-json\/wp\/v2\/artikelen"}],"about":[{"href":"https:\/\/herik.nl\/de\/wp-json\/wp\/v2\/types\/artikelen"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/herik.nl\/de\/wp-json\/wp\/v2\/media\/8794"}],"wp:attachment":[{"href":"https:\/\/herik.nl\/de\/wp-json\/wp\/v2\/media?parent=9408"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/herik.nl\/de\/wp-json\/wp\/v2\/categories?post=9408"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/herik.nl\/de\/wp-json\/wp\/v2\/tags?post=9408"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}